{"id":23680,"date":"2024-03-03T13:01:35","date_gmt":"2024-03-03T09:31:35","guid":{"rendered":"https:\/\/avantile.co\/?page_id=23680"},"modified":"2026-02-05T13:26:32","modified_gmt":"2026-02-05T09:56:32","slug":"%d8%a7%d8%a8%d8%b9%d8%a7%d8%af-60x60","status":"publish","type":"page","link":"https:\/\/avantile.co\/fa\/%d8%a7%d8%a8%d8%b9%d8%a7%d8%af-60x60\/","title":{"rendered":"\u0627\u0628\u0639\u0627\u062f 60\u00d760"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"23680\" class=\"elementor elementor-23680\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f421c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"1f421c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1666023\" data-id=\"1666023\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c180459 elementor-widget elementor-widget-image\" data-id=\"c180459\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%ab%d9%85%db%8c%d9%86-60x60\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-29213 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/samin-60\u00d760-matt-scaled-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/samin-60\u00d760-matt-scaled-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/samin-60\u00d760-matt-scaled-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/samin-60\u00d760-matt-scaled-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/samin-60\u00d760-matt-scaled-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/samin-60\u00d760-matt-scaled-1-1536x1536.jpg 1536w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/samin-60\u00d760-matt-scaled-1-2048x2048.jpg 2048w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/samin-60\u00d760-matt-scaled-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/samin-60\u00d760-matt-scaled-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/samin-60\u00d760-matt-scaled-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u062b\u0645\u06cc\u0646<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c40cfa2\" data-id=\"c40cfa2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ceef7b9 elementor-widget elementor-widget-image\" data-id=\"ceef7b9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d9%87%d8%ac%d8%b1%d8%aa-60x60\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-29217 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/HEJRAT-60\u00d760-shiny-scaled-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/HEJRAT-60\u00d760-shiny-scaled-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/HEJRAT-60\u00d760-shiny-scaled-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/HEJRAT-60\u00d760-shiny-scaled-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/HEJRAT-60\u00d760-shiny-scaled-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/HEJRAT-60\u00d760-shiny-scaled-1-1536x1536.jpg 1536w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/HEJRAT-60\u00d760-shiny-scaled-1-2048x2048.jpg 2048w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/HEJRAT-60\u00d760-shiny-scaled-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/HEJRAT-60\u00d760-shiny-scaled-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2026\/02\/HEJRAT-60\u00d760-shiny-scaled-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0647\u062c\u0631\u062a<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ecb9c7c\" data-id=\"ecb9c7c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e8fc2d elementor-widget elementor-widget-image\" data-id=\"4e8fc2d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%a2%d8%b1%d8%b3%d9%86%d8%a7\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-28210 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARSENA-shiny-jpeg-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARSENA-shiny-jpeg-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARSENA-shiny-jpeg-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARSENA-shiny-jpeg-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARSENA-shiny-jpeg-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARSENA-shiny-jpeg-1-1536x1536.jpg 1536w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARSENA-shiny-jpeg-1-2048x2048.jpg 2048w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARSENA-shiny-jpeg-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARSENA-shiny-jpeg-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARSENA-shiny-jpeg-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0622\u0631\u0633\u0646\u0627<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e06dd4c elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"e06dd4c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5ba24fa\" data-id=\"5ba24fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba4dbc0 elementor-widget elementor-widget-image\" data-id=\"ba4dbc0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%a2%da%a9%d8%a7%da%98%d9%88-2\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-28418 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29110-shiny-scaled-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29110-shiny-scaled-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29110-shiny-scaled-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29110-shiny-scaled-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29110-shiny-scaled-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29110-shiny-scaled-1-1536x1536.jpg 1536w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29110-shiny-scaled-1-2048x2048.jpg 2048w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29110-shiny-scaled-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29110-shiny-scaled-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29110-shiny-scaled-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0622\u06a9\u0627\u0698\u0648 2<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-383425b\" data-id=\"383425b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f990e0f elementor-widget elementor-widget-image\" data-id=\"f990e0f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%a7%d8%b1%d9%85\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-28422 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29700-Shiny-scaled-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29700-Shiny-scaled-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29700-Shiny-scaled-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29700-Shiny-scaled-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29700-Shiny-scaled-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29700-Shiny-scaled-1-1536x1536.jpg 1536w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29700-Shiny-scaled-1-2048x2048.jpg 2048w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29700-Shiny-scaled-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29700-Shiny-scaled-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29700-Shiny-scaled-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0627\u0631\u0645<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4eae0d1\" data-id=\"4eae0d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93553e4 elementor-widget elementor-widget-image\" data-id=\"93553e4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%a7%d8%b1%d9%85-2\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-28426 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29710-Shiny-scaled-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29710-Shiny-scaled-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29710-Shiny-scaled-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29710-Shiny-scaled-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29710-Shiny-scaled-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29710-Shiny-scaled-1-1536x1536.jpg 1536w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29710-Shiny-scaled-1-2048x2048.jpg 2048w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29710-Shiny-scaled-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29710-Shiny-scaled-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Eram-29710-Shiny-scaled-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0627\u0631\u0645 2<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7044274 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"7044274\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8cd4777\" data-id=\"8cd4777\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bf34d0 elementor-widget elementor-widget-image\" data-id=\"7bf34d0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%b5%d9%86%d9%88%d8%a8%d8%b1\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-28430 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-senobar-21940-shiny-scaled-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-senobar-21940-shiny-scaled-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-senobar-21940-shiny-scaled-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-senobar-21940-shiny-scaled-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-senobar-21940-shiny-scaled-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-senobar-21940-shiny-scaled-1-1536x1536.jpg 1536w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-senobar-21940-shiny-scaled-1-2048x2048.jpg 2048w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-senobar-21940-shiny-scaled-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-senobar-21940-shiny-scaled-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-senobar-21940-shiny-scaled-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0635\u0646\u0648\u0628\u0631<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bdd7c49\" data-id=\"bdd7c49\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-061a9d8 elementor-widget elementor-widget-image\" data-id=\"061a9d8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%a2%da%a9%d8%a7%da%98%d9%88\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-28434 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29100-Shiny-scaled-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29100-Shiny-scaled-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29100-Shiny-scaled-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29100-Shiny-scaled-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29100-Shiny-scaled-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29100-Shiny-scaled-1-1536x1536.jpg 1536w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29100-Shiny-scaled-1-2048x2048.jpg 2048w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29100-Shiny-scaled-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29100-Shiny-scaled-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Akazhoo-29100-Shiny-scaled-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0622\u06a9\u0627\u0698\u0648<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-696199a\" data-id=\"696199a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-501f0a7 elementor-widget elementor-widget-image\" data-id=\"501f0a7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%a7%d8%b1%d8%b3\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-28438 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Aras-29550-Shiny-scaled-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Aras-29550-Shiny-scaled-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Aras-29550-Shiny-scaled-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Aras-29550-Shiny-scaled-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Aras-29550-Shiny-scaled-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Aras-29550-Shiny-scaled-1-1536x1536.jpg 1536w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Aras-29550-Shiny-scaled-1-2048x2048.jpg 2048w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Aras-29550-Shiny-scaled-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Aras-29550-Shiny-scaled-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/10\/pasargadceram-Aras-29550-Shiny-scaled-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0627\u0631\u0633<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c574417 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"4c574417\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-223e2d47\" data-id=\"223e2d47\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13a5e6b elementor-widget elementor-widget-image\" data-id=\"13a5e6b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%d8%a2%d8%aa%db%8c%d8%a7-60x60\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-27966 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/05\/ATIA-60\u00d760-shiny-web-version-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/05\/ATIA-60\u00d760-shiny-web-version-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/05\/ATIA-60\u00d760-shiny-web-version-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/05\/ATIA-60\u00d760-shiny-web-version-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/05\/ATIA-60\u00d760-shiny-web-version-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/05\/ATIA-60\u00d760-shiny-web-version-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/05\/ATIA-60\u00d760-shiny-web-version-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/05\/ATIA-60\u00d760-shiny-web-version-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/05\/ATIA-60\u00d760-shiny-web-version.jpg 866w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0622\u062a\u06cc\u0627<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-314dc1f3\" data-id=\"314dc1f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e9d32a elementor-widget elementor-widget-image\" data-id=\"7e9d32a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%b1%d9%88%d9%86%d8%a7%d9%87%db%8c-60x60\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"787\" height=\"787\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-26324 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 787px) 100vw, 787px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/10\/Ronahi-60\u00d760-shiny-web-version.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/10\/Ronahi-60\u00d760-shiny-web-version.jpg 787w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/10\/Ronahi-60\u00d760-shiny-web-version-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/10\/Ronahi-60\u00d760-shiny-web-version-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/10\/Ronahi-60\u00d760-shiny-web-version-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/10\/Ronahi-60\u00d760-shiny-web-version-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/10\/Ronahi-60\u00d760-shiny-web-version-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0631\u0648\u0646\u0627\u0647\u06cc<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-131f3a74\" data-id=\"131f3a74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15d819b elementor-widget elementor-widget-image\" data-id=\"15d819b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%b3%d9%88%db%8c%d9%86-60x60\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-27634 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/sevin-60\u00d760-matt-web-version-2-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/sevin-60\u00d760-matt-web-version-2-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/sevin-60\u00d760-matt-web-version-2-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/sevin-60\u00d760-matt-web-version-2-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/sevin-60\u00d760-matt-web-version-2-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/sevin-60\u00d760-matt-web-version-2-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/sevin-60\u00d760-matt-web-version-2-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/sevin-60\u00d760-matt-web-version-2-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/sevin-60\u00d760-matt-web-version-2.jpg 1476w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0633\u0648\u06cc\u0646<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4394be9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"4394be9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-26684622\" data-id=\"26684622\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76bd72b elementor-widget elementor-widget-image\" data-id=\"76bd72b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%a2%d9%84%da%a9%d9%88-60x60\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-27638 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Aleco-60-polished-Web-aplication-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Aleco-60-polished-Web-aplication-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Aleco-60-polished-Web-aplication-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Aleco-60-polished-Web-aplication-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Aleco-60-polished-Web-aplication-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Aleco-60-polished-Web-aplication-1-1536x1536.jpg 1536w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Aleco-60-polished-Web-aplication-1-2048x2048.jpg 2048w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Aleco-60-polished-Web-aplication-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Aleco-60-polished-Web-aplication-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Aleco-60-polished-Web-aplication-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0622\u0644\u06a9\u0648<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dedf6d6\" data-id=\"dedf6d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55cc8953 elementor-widget elementor-widget-image\" data-id=\"55cc8953\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%d8%b1%d8%a7%db%8c%d8%a7%d9%86\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-22390 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rayan-60\u00d760-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rayan-60\u00d760-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rayan-60\u00d760-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rayan-60\u00d760-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rayan-60\u00d760-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rayan-60\u00d760-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rayan-60\u00d760-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rayan-60\u00d760-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rayan-60\u00d760.jpg 1181w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0631\u0627\u06cc\u0627\u0646<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-715dfd5c\" data-id=\"715dfd5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e27de63 elementor-widget elementor-widget-image\" data-id=\"1e27de63\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%d9%be%d8%a7%d8%af%d9%88%d8%b1%d8%a7\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-22385 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/padora-60\u00d760-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/padora-60\u00d760-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/padora-60\u00d760-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/padora-60\u00d760-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/padora-60\u00d760-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/padora-60\u00d760-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/padora-60\u00d760-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/padora-60\u00d760-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/padora-60\u00d760.jpg 1181w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u067e\u0627\u062f\u0648\u0631\u0627<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b0b1cc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"1b0b1cc0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6be89580\" data-id=\"6be89580\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f42ba34 elementor-widget elementor-widget-image\" data-id=\"f42ba34\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%d8%a2%d9%84%d8%a7%d8%b1%db%8c%d8%a7\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-22413 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Alariya-60\u00d760-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Alariya-60\u00d760-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Alariya-60\u00d760-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Alariya-60\u00d760-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Alariya-60\u00d760-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Alariya-60\u00d760-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Alariya-60\u00d760-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Alariya-60\u00d760-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Alariya-60\u00d760.jpg 1181w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0622\u0644\u0627\u0631\u06cc\u0627<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2dd15b8d\" data-id=\"2dd15b8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b2f65f4 elementor-widget elementor-widget-image\" data-id=\"7b2f65f4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%d8%b3%db%8c%d8%aa%d8%a7%d8%af%d9%84\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-22407 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/3-Sitadel-60\u00d760-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/3-Sitadel-60\u00d760-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/3-Sitadel-60\u00d760-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/3-Sitadel-60\u00d760-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/3-Sitadel-60\u00d760-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/3-Sitadel-60\u00d760-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/3-Sitadel-60\u00d760-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/3-Sitadel-60\u00d760-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/3-Sitadel-60\u00d760.jpg 1181w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0633\u06cc\u062a\u0627\u062f\u0644<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-55596f3f\" data-id=\"55596f3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40d67397 elementor-widget elementor-widget-image\" data-id=\"40d67397\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%d8%ac%d9%88%d8%b1%d8%af%d9%86\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"802\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-22401 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 802px) 100vw, 802px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Jordan-60\u00d760-802x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Jordan-60\u00d760-802x800.jpg 802w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Jordan-60\u00d760-301x300.jpg 301w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Jordan-60\u00d760-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Jordan-60\u00d760-768x766.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Jordan-60\u00d760-860x858.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Jordan-60\u00d760-430x429.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Jordan-60\u00d760-700x698.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Jordan-60\u00d760.jpg 1181w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u062c\u0648\u0631\u062f\u0646<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ed62f15 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"3ed62f15\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5eb25657\" data-id=\"5eb25657\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a69e26f elementor-widget elementor-widget-image\" data-id=\"7a69e26f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%da%a9%d8%a7%d9%be%db%8c%d8%b1%d8%a7\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-22425 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Kapira-60\u00d760-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Kapira-60\u00d760-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Kapira-60\u00d760-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Kapira-60\u00d760-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Kapira-60\u00d760-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Kapira-60\u00d760-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Kapira-60\u00d760-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Kapira-60\u00d760-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Kapira-60\u00d760.jpg 1181w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u06a9\u0627\u067e\u0631\u06cc\u0627<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-64f51798\" data-id=\"64f51798\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7787f333 elementor-widget elementor-widget-image\" data-id=\"7787f333\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%d8%a2%d8%b1%d8%a7%d9%85-%d8%aa%db%8c%d8%b1%d9%87\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-23357 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Aram-Dark-60\u00d760-MATT-web-version-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Aram-Dark-60\u00d760-MATT-web-version-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Aram-Dark-60\u00d760-MATT-web-version-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Aram-Dark-60\u00d760-MATT-web-version-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Aram-Dark-60\u00d760-MATT-web-version-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Aram-Dark-60\u00d760-MATT-web-version-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Aram-Dark-60\u00d760-MATT-web-version-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Aram-Dark-60\u00d760-MATT-web-version-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Aram-Dark-60\u00d760-MATT-web-version.jpg 1299w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0622\u0631\u0627\u0645 \u062a\u06cc\u0631\u0647<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1e057fc6\" data-id=\"1e057fc6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1602ec59 elementor-widget elementor-widget-image\" data-id=\"1602ec59\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%d9%84%db%8c%d8%b2%d8%a7\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-22419 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Liza-grey-60\u00d760-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Liza-grey-60\u00d760-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Liza-grey-60\u00d760-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Liza-grey-60\u00d760-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Liza-grey-60\u00d760-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Liza-grey-60\u00d760-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Liza-grey-60\u00d760-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Liza-grey-60\u00d760-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Liza-grey-60\u00d760.jpg 1181w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0644\u06cc\u0632\u0627<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-202720b elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"202720b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-206a288\" data-id=\"206a288\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58ec25d elementor-widget elementor-widget-image\" data-id=\"58ec25d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%d9%88%d8%a7%d9%84%d9%86%d8%aa%db%8c%d9%86%d8%a7-%d8%aa%db%8c%d8%b1%d9%87\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-22371 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/valentina-30150-60\u00d760-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/valentina-30150-60\u00d760-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/valentina-30150-60\u00d760-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/valentina-30150-60\u00d760-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/valentina-30150-60\u00d760-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/valentina-30150-60\u00d760-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/valentina-30150-60\u00d760-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/valentina-30150-60\u00d760-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/valentina-30150-60\u00d760.jpg 1181w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0648\u0627\u0644\u0646\u062a\u06cc\u0646\u0627 \u062a\u06cc\u0631\u0647<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d8f401b\" data-id=\"d8f401b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b2293b elementor-widget elementor-widget-image\" data-id=\"2b2293b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d9%be%d8%a7%d8%b1%d9%86%d8%af\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"788\" height=\"788\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-22381 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 788px) 100vw, 788px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/1-Parand-60\u00d760.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/1-Parand-60\u00d760.jpg 788w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/1-Parand-60\u00d760-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/1-Parand-60\u00d760-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/1-Parand-60\u00d760-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/1-Parand-60\u00d760-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/1-Parand-60\u00d760-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u067e\u0627\u0631\u0646\u062f<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c5b0134\" data-id=\"c5b0134\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bf0509 elementor-widget elementor-widget-image\" data-id=\"5bf0509\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%d9%88%d8%a7%d9%84%d9%86%d8%aa%db%8c%d9%86%d8%a7-%d8%b1%d9%88%d8%b4%d9%86\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-22360 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Valentina-60\u00d760-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Valentina-60\u00d760-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Valentina-60\u00d760-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Valentina-60\u00d760-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Valentina-60\u00d760-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Valentina-60\u00d760-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Valentina-60\u00d760-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Valentina-60\u00d760-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Valentina-60\u00d760.jpg 1181w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0648\u0627\u0644\u0646\u062a\u06cc\u0646\u0627 \u0631\u0648\u0634\u0646<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a87dac elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"3a87dac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3699e28\" data-id=\"3699e28\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3e293b elementor-widget elementor-widget-image\" data-id=\"f3e293b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%a2%d8%b1%db%8c%d9%86\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-28206 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARIAN-shiny-jpeg-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARIAN-shiny-jpeg-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARIAN-shiny-jpeg-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARIAN-shiny-jpeg-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARIAN-shiny-jpeg-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARIAN-shiny-jpeg-1-1536x1536.jpg 1536w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARIAN-shiny-jpeg-1-2048x2048.jpg 2048w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARIAN-shiny-jpeg-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARIAN-shiny-jpeg-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/ARIAN-shiny-jpeg-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0622\u0631\u06cc\u0646<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-021d987\" data-id=\"021d987\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66f054c elementor-widget elementor-widget-image\" data-id=\"66f054c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/%d8%b1%d8%a7%d8%a8%d9%84\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-22395 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rabel-60\u00d760-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rabel-60\u00d760-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rabel-60\u00d760-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rabel-60\u00d760-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rabel-60\u00d760-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rabel-60\u00d760-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rabel-60\u00d760-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rabel-60\u00d760-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2024\/02\/Rabel-60\u00d760.jpg 1181w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0631\u0627\u0628\u0644<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b6ccb53\" data-id=\"b6ccb53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3833a00 elementor-widget elementor-widget-image\" data-id=\"3833a00\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%b3%d8%a7%d9%86%db%8c%d9%84-60x60\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"787\" height=\"787\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-27630 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 787px) 100vw, 787px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Sanil-60\u00d760-matt-Web-Version-1.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Sanil-60\u00d760-matt-Web-Version-1.jpg 787w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Sanil-60\u00d760-matt-Web-Version-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Sanil-60\u00d760-matt-Web-Version-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Sanil-60\u00d760-matt-Web-Version-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Sanil-60\u00d760-matt-Web-Version-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/02\/Sanil-60\u00d760-matt-Web-Version-1-700x700.jpg 700w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0633\u0627\u0646\u06cc\u0644<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80ce3aa elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"80ce3aa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-10b4687\" data-id=\"10b4687\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1ac8e11\" data-id=\"1ac8e11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-090bac0 elementor-widget elementor-widget-image\" data-id=\"090bac0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/avantile.co\/fa\/%d8%a2%d9%84%d9%88%d8%af%db%8c\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/avantile.co\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"elementor-animation-shrink attachment-large size-large wp-image-28202 wd-lazy-load wd-lazy-fade\" alt=\"\" srcset=\"\" sizes=\"(max-width: 800px) 100vw, 800px\" data-wood-src=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/Alodi-shiny-60\u00d760-cream-Web-version-1-800x800.jpg\" data-srcset=\"https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/Alodi-shiny-60\u00d760-cream-Web-version-1-800x800.jpg 800w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/Alodi-shiny-60\u00d760-cream-Web-version-1-300x300.jpg 300w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/Alodi-shiny-60\u00d760-cream-Web-version-1-150x150.jpg 150w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/Alodi-shiny-60\u00d760-cream-Web-version-1-768x768.jpg 768w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/Alodi-shiny-60\u00d760-cream-Web-version-1-860x860.jpg 860w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/Alodi-shiny-60\u00d760-cream-Web-version-1-430x430.jpg 430w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/Alodi-shiny-60\u00d760-cream-Web-version-1-700x700.jpg 700w, https:\/\/avantile.co\/wp-content\/uploads\/2025\/09\/Alodi-shiny-60\u00d760-cream-Web-version-1.jpg 866w\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u0622\u0644\u0648\u062f\u06cc<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-75a096c\" data-id=\"75a096c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u062b\u0645\u06cc\u0646 \u0647\u062c\u0631\u062a \u0622\u0631\u0633\u0646\u0627 \u0622\u06a9\u0627\u0698\u0648 2 \u0627\u0631\u0645 \u0627\u0631\u0645 2 \u0635\u0646\u0648\u0628\u0631 \u0622\u06a9\u0627\u0698\u0648 \u0627\u0631\u0633 \u0622\u062a\u06cc\u0627 \u0631\u0648\u0646\u0627\u0647\u06cc \u0633\u0648\u06cc\u0646 \u0622\u0644\u06a9\u0648 \u0631\u0627\u06cc\u0627\u0646 \u067e\u0627\u062f\u0648\u0631\u0627 \u0622\u0644\u0627\u0631\u06cc\u0627 \u0633\u06cc\u062a\u0627\u062f\u0644 \u062c\u0648\u0631\u062f\u0646<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-23680","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/avantile.co\/fa\/wp-json\/wp\/v2\/pages\/23680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avantile.co\/fa\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/avantile.co\/fa\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/avantile.co\/fa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/avantile.co\/fa\/wp-json\/wp\/v2\/comments?post=23680"}],"version-history":[{"count":34,"href":"https:\/\/avantile.co\/fa\/wp-json\/wp\/v2\/pages\/23680\/revisions"}],"predecessor-version":[{"id":29223,"href":"https:\/\/avantile.co\/fa\/wp-json\/wp\/v2\/pages\/23680\/revisions\/29223"}],"wp:attachment":[{"href":"https:\/\/avantile.co\/fa\/wp-json\/wp\/v2\/media?parent=23680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}